{"id":9547,"date":"2011-01-13T19:02:00","date_gmt":"2011-01-13T19:02:00","guid":{"rendered":"http:\/\/www.civiltalaica.it\/cms\/index.php\/vietato-ai-minori.html"},"modified":"2011-01-13T19:02:00","modified_gmt":"2011-01-13T19:02:00","slug":"vietato-ai-minori","status":"publish","type":"post","link":"https:\/\/www.civiltalaica.it\/cms\/vietato-ai-minori\/","title":{"rendered":"Vietato ai minori!"},"content":{"rendered":"<p>&nbsp;<img decoding=\"async\" alt=\"\" src=\"http:\/\/2honolulu.it\/wp-content\/uploads\/2008\/12\/bonobo.jpg\" style=\"width: 460px; height: 320px\" \/><\/p>\n<p align=\"justify\" style=\"margin-bottom: 0cm\">\t<span style=\"font-family: tahoma, geneva, sans-serif\"><span style=\"font-size: 14px\">Pu&ograve; capitare di accendere il televisore ed osservare una coppia guardarsi negli occhi, avvicinarsi, baciarsi sulle labbra, a volte con la lingua, toccarsi, strofinarsi e finire a fare sesso in qualsivoglia posizione per poi rimanere avvinghiata in un abbraccio al termine dell&rsquo;amplesso. Tutto questo in fascia protetta e dopo aver sintonizzato l&rsquo;apparecchio sul canale del <span lang=\"en-US\">National Geographic<\/span>. Com&rsquo;&egrave; possibile? Semplice, perch&eacute; non stiamo parlando di una coppia di umani, ma quanto di pi&ugrave; simile agli umani esiste in natura: <b>i bonobo<\/b>!<\/span><\/span><\/p>\n<p><\/p>\n<p align=\"justify\" style=\"margin-bottom: 0cm\">\t<span style=\"font-family: tahoma, geneva, sans-serif\"><span style=\"font-size: 14px\">Considerati una particolare razza di scimpanz&eacute; fino a qualche decennio fa, i bonobo sono stati recentemente riconosciuti come una specie vera e propria (<i>Pan Paniscus<\/i>), e sono stati studiati sempre pi&ugrave; in dettaglio a partire dagli anni novanta, svelando un vero e proprio mondo di complesse abitudini e comportamenti sociali inaspettati.<\/span><\/span><\/p>\n<p><\/p>\n<p align=\"justify\" style=\"margin-bottom: 0cm\">\t<span style=\"font-family: tahoma, geneva, sans-serif\"><span style=\"font-size: 14px\">Cugini degli esseri umani (con cui si stima condividano <b>almeno il 98% del genoma<\/b>) e ovviamente degli scimpanz&eacute; (qui la somiglianza genetica supera il 99%), i bonobo sono l&rsquo;unica specie animale, oltre all&rsquo;uomo, a praticare sesso anche al di fuori dei periodi riproduttivi delle femmine. Non solo, i bonobo sono stati osservati <b>accoppiarsi ventre a ventre<\/b>, praticare sesso orale e masturbarsi. Nelle comunit&agrave; di bonobo nessuna femmina appartiene ad un singolo maschio, ma tutti fanno sesso con tutti, come attivit&agrave; ricreativa o per appianare qualche diverbio. Questo in particolare sembra essere il principale vantaggio evolutivo prodotto da questa mutazione comportamentale: i bonobo risultano tuttora i primati meno violenti in natura (includendo l&rsquo;uomo). Non si &egrave; mai osservato un bonobo uccidere un suo simile, n&eacute; praticare violenza su di un cucciolo, anche perch&eacute; non &egrave; escluso, vista la peculiare promiscuit&agrave;, che si tratti del proprio figlio.<\/span><\/span><\/p>\n<p><\/p>\n<p align=\"justify\" style=\"margin-bottom: 0cm\">\t<span style=\"font-family: tahoma, geneva, sans-serif\"><span style=\"font-size: 14px\">I bonobo di certo litigano, ma hanno escogitato un modo sorprendente per evitare di finire alle mani: <b>il sesso, anche omosessuale<\/b>. Non &egrave; raro osservare due femmine che si strofinano i genitali o due maschi che si scambiano ardite carezze per stemperare l&rsquo;aggressivit&agrave;. La comunit&agrave; scientifica &egrave; sempre pi&ugrave; incline a ritenere che lo stesso vantaggio evolutivo sia stato guadagnato dal genere <i>Homo<\/i>, quando anche per noi il sesso ha smesso di essere solo un mezzo per procreare ed &egrave; diventato un comportamento sociale, oltre che un piacere.<\/span><\/span><\/p>\n<p><\/p>\n<p align=\"justify\" style=\"margin-bottom: 0cm\">\t<span style=\"font-family: tahoma, geneva, sans-serif\"><span style=\"font-size: 14px\">La cosa certamente bizzarra &egrave; che tra gli esseri umani (almeno tra quelli con abitudini pi&ugrave; simili agli scimpanz&eacute; che ai bonobo) c&rsquo;&egrave; ancora chi asserisce che l&rsquo;omosessualit&agrave; sia &ldquo;contro natura&rdquo; e che il sesso ricreativo sia segno di mancanza di valori. Sembra che queste persone non si siano mai seriamente fermate ad osservarla, la natura, continuando a pensare che la verit&agrave; risieda in qualche libro antico.<\/span><\/span><\/p>\n<p><\/p>\n<p align=\"justify\" style=\"margin-bottom: 0cm\">\t<span style=\"font-family: tahoma, geneva, sans-serif\"><span style=\"font-size: 14px\">Considerando invece l&rsquo;allegria e la serenit&agrave; dei nostri cugini pelosi, viene davvero da chiedersi quale sia la <b>specie pi&ugrave; evoluta del pianeta<\/b>.<\/p>\n<p>\t<strong>Marcello Angelone<\/strong><\/span><\/span><\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Pu&ograve; capitare di accendere il televisore ed osservare una coppia guardarsi negli occhi, avvicinarsi, baciarsi sulle labbra, a volte con la lingua, toccarsi, strofinarsi e finire a fare sesso in qualsivoglia posizione per poi rimanere avvinghiata in un abbraccio al termine dell&rsquo;amplesso. Tutto questo in fascia protetta e dopo aver sintonizzato l&rsquo;apparecchio sul canale [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[228],"tags":[793,794,264],"class_list":["post-9547","post","type-post","status-publish","format-standard","hentry","category-blog","tag-bonobo","tag-marcello-angelone","tag-omosessualita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vietato ai minori! - Associazione Culturale Civilt\u00e0 Laica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.civiltalaica.it\/cms\/vietato-ai-minori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vietato ai minori! - Associazione Culturale Civilt\u00e0 Laica\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Pu&ograve; capitare di accendere il televisore ed osservare una coppia guardarsi negli occhi, avvicinarsi, baciarsi sulle labbra, a volte con la lingua, toccarsi, strofinarsi e finire a fare sesso in qualsivoglia posizione per poi rimanere avvinghiata in un abbraccio al termine dell&rsquo;amplesso. Tutto questo in fascia protetta e dopo aver sintonizzato l&rsquo;apparecchio sul canale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.civiltalaica.it\/cms\/vietato-ai-minori\/\" \/>\n<meta property=\"og:site_name\" content=\"Associazione Culturale Civilt\u00e0 Laica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/civiltalaica\" \/>\n<meta property=\"article:published_time\" content=\"2011-01-13T19:02:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/2honolulu.it\/wp-content\/uploads\/2008\/12\/bonobo.jpg\" \/>\n<meta name=\"author\" content=\"alexjc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"alexjc\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/vietato-ai-minori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/vietato-ai-minori\\\/\"},\"author\":{\"name\":\"alexjc\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#\\\/schema\\\/person\\\/4efef56f866329a1e0943eb27336df1d\"},\"headline\":\"Vietato ai minori!\",\"datePublished\":\"2011-01-13T19:02:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/vietato-ai-minori\\\/\"},\"wordCount\":500,\"image\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/vietato-ai-minori\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/2honolulu.it\\\/wp-content\\\/uploads\\\/2008\\\/12\\\/bonobo.jpg\",\"keywords\":[\"bonobo\",\"marcello angelone\",\"omosessualit\u00e0\"],\"articleSection\":[\"blog\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/vietato-ai-minori\\\/\",\"url\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/vietato-ai-minori\\\/\",\"name\":\"Vietato ai minori! - Associazione Culturale Civilt\u00e0 Laica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/vietato-ai-minori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/vietato-ai-minori\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/2honolulu.it\\\/wp-content\\\/uploads\\\/2008\\\/12\\\/bonobo.jpg\",\"datePublished\":\"2011-01-13T19:02:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#\\\/schema\\\/person\\\/4efef56f866329a1e0943eb27336df1d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/vietato-ai-minori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/vietato-ai-minori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/vietato-ai-minori\\\/#primaryimage\",\"url\":\"http:\\\/\\\/2honolulu.it\\\/wp-content\\\/uploads\\\/2008\\\/12\\\/bonobo.jpg\",\"contentUrl\":\"http:\\\/\\\/2honolulu.it\\\/wp-content\\\/uploads\\\/2008\\\/12\\\/bonobo.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/vietato-ai-minori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vietato ai minori!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/\",\"name\":\"Associazione Culturale Civilt\u00e0 Laica\",\"description\":\"Per un movimento culturale volto a difendere la Laicit\u00e0 dello Stato.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#\\\/schema\\\/person\\\/4efef56f866329a1e0943eb27336df1d\",\"name\":\"alexjc\",\"url\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/author\\\/alexjc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vietato ai minori! - Associazione Culturale Civilt\u00e0 Laica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.civiltalaica.it\/cms\/vietato-ai-minori\/","og_locale":"it_IT","og_type":"article","og_title":"Vietato ai minori! - Associazione Culturale Civilt\u00e0 Laica","og_description":"&nbsp; Pu&ograve; capitare di accendere il televisore ed osservare una coppia guardarsi negli occhi, avvicinarsi, baciarsi sulle labbra, a volte con la lingua, toccarsi, strofinarsi e finire a fare sesso in qualsivoglia posizione per poi rimanere avvinghiata in un abbraccio al termine dell&rsquo;amplesso. Tutto questo in fascia protetta e dopo aver sintonizzato l&rsquo;apparecchio sul canale [&hellip;]","og_url":"https:\/\/www.civiltalaica.it\/cms\/vietato-ai-minori\/","og_site_name":"Associazione Culturale Civilt\u00e0 Laica","article_publisher":"https:\/\/www.facebook.com\/civiltalaica","article_published_time":"2011-01-13T19:02:00+00:00","og_image":[{"url":"http:\/\/2honolulu.it\/wp-content\/uploads\/2008\/12\/bonobo.jpg","type":"","width":"","height":""}],"author":"alexjc","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"alexjc","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.civiltalaica.it\/cms\/vietato-ai-minori\/#article","isPartOf":{"@id":"https:\/\/www.civiltalaica.it\/cms\/vietato-ai-minori\/"},"author":{"name":"alexjc","@id":"https:\/\/www.civiltalaica.it\/cms\/#\/schema\/person\/4efef56f866329a1e0943eb27336df1d"},"headline":"Vietato ai minori!","datePublished":"2011-01-13T19:02:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.civiltalaica.it\/cms\/vietato-ai-minori\/"},"wordCount":500,"image":{"@id":"https:\/\/www.civiltalaica.it\/cms\/vietato-ai-minori\/#primaryimage"},"thumbnailUrl":"http:\/\/2honolulu.it\/wp-content\/uploads\/2008\/12\/bonobo.jpg","keywords":["bonobo","marcello angelone","omosessualit\u00e0"],"articleSection":["blog"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.civiltalaica.it\/cms\/vietato-ai-minori\/","url":"https:\/\/www.civiltalaica.it\/cms\/vietato-ai-minori\/","name":"Vietato ai minori! - Associazione Culturale Civilt\u00e0 Laica","isPartOf":{"@id":"https:\/\/www.civiltalaica.it\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.civiltalaica.it\/cms\/vietato-ai-minori\/#primaryimage"},"image":{"@id":"https:\/\/www.civiltalaica.it\/cms\/vietato-ai-minori\/#primaryimage"},"thumbnailUrl":"http:\/\/2honolulu.it\/wp-content\/uploads\/2008\/12\/bonobo.jpg","datePublished":"2011-01-13T19:02:00+00:00","author":{"@id":"https:\/\/www.civiltalaica.it\/cms\/#\/schema\/person\/4efef56f866329a1e0943eb27336df1d"},"breadcrumb":{"@id":"https:\/\/www.civiltalaica.it\/cms\/vietato-ai-minori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.civiltalaica.it\/cms\/vietato-ai-minori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.civiltalaica.it\/cms\/vietato-ai-minori\/#primaryimage","url":"http:\/\/2honolulu.it\/wp-content\/uploads\/2008\/12\/bonobo.jpg","contentUrl":"http:\/\/2honolulu.it\/wp-content\/uploads\/2008\/12\/bonobo.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.civiltalaica.it\/cms\/vietato-ai-minori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.civiltalaica.it\/cms\/"},{"@type":"ListItem","position":2,"name":"Vietato ai minori!"}]},{"@type":"WebSite","@id":"https:\/\/www.civiltalaica.it\/cms\/#website","url":"https:\/\/www.civiltalaica.it\/cms\/","name":"Associazione Culturale Civilt\u00e0 Laica","description":"Per un movimento culturale volto a difendere la Laicit\u00e0 dello Stato.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.civiltalaica.it\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.civiltalaica.it\/cms\/#\/schema\/person\/4efef56f866329a1e0943eb27336df1d","name":"alexjc","url":"https:\/\/www.civiltalaica.it\/cms\/author\/alexjc\/"}]}},"_links":{"self":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts\/9547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/comments?post=9547"}],"version-history":[{"count":0,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts\/9547\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/media?parent=9547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/categories?post=9547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/tags?post=9547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}