{"id":9278,"date":"2008-02-23T11:02:00","date_gmt":"2008-02-23T11:02:00","guid":{"rendered":"http:\/\/www.civiltalaica.it\/cms\/index.php\/lettera-aperta-a-giuliano-ferrara.html"},"modified":"2008-02-23T11:02:00","modified_gmt":"2008-02-23T11:02:00","slug":"lettera-aperta-a-giuliano-ferrara","status":"publish","type":"post","link":"https:\/\/www.civiltalaica.it\/cms\/lettera-aperta-a-giuliano-ferrara\/","title":{"rendered":"Lettera aperta a Giuliano Ferrara&#8230;"},"content":{"rendered":"<p align=\"left\"><em>La lettera che segue &egrave; stata presa direttamente dal <a target=\"_blank\" href=\"http:\/\/www.distrofici.it\/blog\/blog_comments.php?id=2402\">blog di Anita,<\/a> ragazza di 18 anni malata di distrofia muscolare, &egrave; stata pubblicata anche su Panorama.it.<\/em><\/p>\n<p align=\"left\"><em>SI attende&nbsp;la risposta del difensore dei feti malati<\/em><\/p>\n<p align=\"right\"><em><strong>redazione[at]civiltalaica.it<\/strong><\/em><\/p>\n<p align=\"justify\">Io sono il feto malato&#8230;.<br \/>\nMi chiamo Anita ho 18 anni e sono un ex feto malato&#8230;ora sono una ragazza &ldquo;malata&rdquo;,ho una malattia neuromuscolare,in inglese SMA,molto simile alla sclerosi laterale amiotrofica , solo che la Sma colpisce i bambini. Si divide in tre forme la prima ossia la pi&ugrave; grave impedisce quasi ogni movimento e si manifesta nei primi mesi di vita del bambino e colpisce anche l&rsquo;apparato respiratorio e spesso provoca la morte entro i primi anni di vita,la seconda (della quale sono affetta io) si manifesta entro l&rsquo;anno di vita e impedisce di camminare e porta alla scogliosi e anch&rsquo;essa colpisce l&rsquo;apparato respiratorio e porta all&rsquo;utilizzo di un respiratore durante la notte e fin dai primi anni di vita all&rsquo;utilizzo di una carrozzina elettrica,la terza &egrave; la meno grave ma porta comunque negli anni all&rsquo;utilizzo della carrozzina. E&rsquo; una malattia genetica rara &egrave; quindi non rientra nelle patologie che vengono sottoposte al controllo prima della nascita, a meno che non ci siano casi in famiglia.Suppongo che la domanda sorga spontanea&#8230;sono contenta di essere nata? Ovviamente si, sono fiera di ci&ograve; che sono, amo la mia vita con tutte le sue difficolt&agrave;,vivo una vita piena molto pi&ugrave; piena di quanto si possa immaginare,ho una famiglia stupenda che mi ha voluta,che quando ha saputo delle mia malattia ha avuto un primo momento di sconforto poi si &egrave; rimboccata le maniche e mi ha cresciuto normalmente come tutti gli altri bambini&#8230;Ora mi crescono come una ragazza &ldquo;normale&rdquo;(esiste la normalit&agrave;?)&#8230;Nella mia vita sono passata da tante situazioni, dai reparti di neurologia pediatrica alle rianimazioni&#8230;ai convegni sulla mia malattia,che sono dei raduni carichi di speranza,di dolore, di gioia di vivere&#8230;.Ho visto genitori straziati dal dolore di aver perso un figlio,tanto velocemente e con tante sofferenze&#8230;ho visto bimbi di 2 anni su una carrozzina attaccati ad un respiratore impossibilitati a muoversi dalla testa ai piedi,eppure carichi di vita, ne ho visti altri con lo sguardo stanco&#8230;Chi si batte tanto&nbsp; a parlare di vita, di diritto alla vita, temo che ne sappia ben poco del vero valore di questa parola, forse parliamo tanto di diritto alla vita di questi tempi perch&egrave; ci sembra di vivere passivamente e allora ci battiamo pi&ugrave; che per il diritto di vita degli altri per riaccendere la nostra volont&agrave; di vivere.Qualcuno potrebbe dirmi &ldquo;se tua madre avesse saputo della tua malattia tu non saresti nata&rdquo;, si &egrave; vero, mia madre avrebbe avuto il difficilissimo e dolorosissimo compito di scegliere se perdere un figlio o metterlo al mondo anche se malato&#8230; Bene mia madre dopo aver avuto me ha provato a darmi un fratellino e ha fatto tutti gli esami ed &egrave; risultato che anch&rsquo;esso era malato&#8230;potete immaginare la tragedia interna di mia madre&#8230; abortire e perdere un figlio e in un certo senso rinnegarmi o mettere al mondo un bimbo malato (senza sapere quale forma di malattia potesse avere)&#8230;. bene mia madre da donna,da madre, ha preso la decisione pi&ugrave; giusta&#8230;.ossia abortire&#8230;E&rsquo; forse stata un mostro? un&rsquo; assassina? o forse &egrave; stata coraggiosa,saggia, e ha evitato di mettere al mondo un bimbo destinato a soffrire&#8230;.Ognuno la pu&ograve; interpretare come vuole&#8230;ma &egrave; proprio questo il punto, la libert&agrave;. Per libert&agrave; non intendo poter fare ci&ograve; che si vuole (come spesso viene interpretata la libert&agrave;) ma essere liberi di poter compiere una scelta,dolorosa in qualsiasi caso, di non sentirsi dei mostri se si compie uno o l&rsquo;altra scelta. Dio stesso ha fornito all&rsquo;uomo il libero arbitrio&#8230; Concludo&nbsp;&nbsp; rivolgendomi direttamente a lei signor. Ferrara, io personalmente trovo la sua &ldquo;lista-crociata&rdquo; anti-abortista del tutto fuori posto, trovo decisamente inadeguato usare un tema cos&igrave; delicato e che tocca cos&igrave; profondamente e personalmente milioni di donne e di uomini, come campagna elettorale. Lei ha messo sullo stesso piano la moratoria sulla pena di morte e l&rsquo;aborto, trovo difficile comprendere questa comparazione,visto che nel caso della moratoria sulla pena di morte si parla di evitare che persone adulte che hanno compiuto un crimine atroce, e gi&agrave; per questo hanno perso la loro umanit&agrave;,vengano uccise, per evitare che anche la giustizia si disumanizzi, mentre nel caso dell&rsquo;aborto parliamo di donne che si trovano davanti a un bivio atroce e non hanno nessuna colpa se non quella di cercare il meglio per s&egrave; e per i propri figli&#8230;Finisco dicendole che se per lei abortire &egrave; come compiere un&rsquo;omicidio&#8230;bene&#8230;sono fiera che mia madre sia un&rsquo;assassina. Cordiali saluti <\/p>\n<p align=\"right\">\n<strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Anita Pallara 18 anni ex feto malato.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La lettera che segue &egrave; stata presa direttamente dal blog di Anita, ragazza di 18 anni malata di distrofia muscolare, &egrave; stata pubblicata anche su Panorama.it. SI attende&nbsp;la risposta del difensore dei feti malati redazione[at]civiltalaica.it Io sono il feto malato&#8230;. Mi chiamo Anita ho 18 anni e sono un ex feto malato&#8230;ora sono una ragazza [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[228],"tags":[196,418,414,212,250,148,417,415,416],"class_list":["post-9278","post","type-post","status-publish","format-standard","hentry","category-blog","tag-aborto","tag-anita-pallara","tag-giuliano-ferrara","tag-laicismo","tag-laicita","tag-laico","tag-sclerosi-laterale-amiotrofica","tag-sla","tag-sma"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lettera aperta a Giuliano Ferrara... - Associazione Culturale Civilt\u00e0 Laica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.civiltalaica.it\/cms\/lettera-aperta-a-giuliano-ferrara\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lettera aperta a Giuliano Ferrara... - Associazione Culturale Civilt\u00e0 Laica\" \/>\n<meta property=\"og:description\" content=\"La lettera che segue &egrave; stata presa direttamente dal blog di Anita, ragazza di 18 anni malata di distrofia muscolare, &egrave; stata pubblicata anche su Panorama.it. SI attende&nbsp;la risposta del difensore dei feti malati redazione[at]civiltalaica.it Io sono il feto malato&#8230;. Mi chiamo Anita ho 18 anni e sono un ex feto malato&#8230;ora sono una ragazza [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.civiltalaica.it\/cms\/lettera-aperta-a-giuliano-ferrara\/\" \/>\n<meta property=\"og:site_name\" content=\"Associazione Culturale Civilt\u00e0 Laica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/civiltalaica\" \/>\n<meta property=\"article:published_time\" content=\"2008-02-23T11:02:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2017\/06\/logo-cl.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"civiltalaica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"civiltalaica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/lettera-aperta-a-giuliano-ferrara\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/lettera-aperta-a-giuliano-ferrara\\\/\"},\"author\":{\"name\":\"civiltalaica\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#\\\/schema\\\/person\\\/128c47163e4fe358041e5b6d4de101ff\"},\"headline\":\"Lettera aperta a Giuliano Ferrara&#8230;\",\"datePublished\":\"2008-02-23T11:02:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/lettera-aperta-a-giuliano-ferrara\\\/\"},\"wordCount\":897,\"keywords\":[\"aborto\",\"anita pallara\",\"giuliano ferrara\",\"laicismo\",\"laicit\u00e0\",\"laico\",\"sclerosi laterale amiotrofica\",\"sla\",\"sma\"],\"articleSection\":[\"blog\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/lettera-aperta-a-giuliano-ferrara\\\/\",\"url\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/lettera-aperta-a-giuliano-ferrara\\\/\",\"name\":\"Lettera aperta a Giuliano Ferrara... - Associazione Culturale Civilt\u00e0 Laica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#website\"},\"datePublished\":\"2008-02-23T11:02:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#\\\/schema\\\/person\\\/128c47163e4fe358041e5b6d4de101ff\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/lettera-aperta-a-giuliano-ferrara\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/lettera-aperta-a-giuliano-ferrara\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/lettera-aperta-a-giuliano-ferrara\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lettera aperta a Giuliano Ferrara&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/\",\"name\":\"Associazione Culturale Civilt\u00e0 Laica\",\"description\":\"Per un movimento culturale volto a difendere la Laicit\u00e0 dello Stato.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#\\\/schema\\\/person\\\/128c47163e4fe358041e5b6d4de101ff\",\"name\":\"civiltalaica\",\"url\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/author\\\/civiltalaica\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lettera aperta a Giuliano Ferrara... - Associazione Culturale Civilt\u00e0 Laica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.civiltalaica.it\/cms\/lettera-aperta-a-giuliano-ferrara\/","og_locale":"it_IT","og_type":"article","og_title":"Lettera aperta a Giuliano Ferrara... - Associazione Culturale Civilt\u00e0 Laica","og_description":"La lettera che segue &egrave; stata presa direttamente dal blog di Anita, ragazza di 18 anni malata di distrofia muscolare, &egrave; stata pubblicata anche su Panorama.it. SI attende&nbsp;la risposta del difensore dei feti malati redazione[at]civiltalaica.it Io sono il feto malato&#8230;. Mi chiamo Anita ho 18 anni e sono un ex feto malato&#8230;ora sono una ragazza [&hellip;]","og_url":"https:\/\/www.civiltalaica.it\/cms\/lettera-aperta-a-giuliano-ferrara\/","og_site_name":"Associazione Culturale Civilt\u00e0 Laica","article_publisher":"https:\/\/www.facebook.com\/civiltalaica","article_published_time":"2008-02-23T11:02:00+00:00","og_image":[{"width":400,"height":180,"url":"https:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2017\/06\/logo-cl.png","type":"image\/png"}],"author":"civiltalaica","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"civiltalaica","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.civiltalaica.it\/cms\/lettera-aperta-a-giuliano-ferrara\/#article","isPartOf":{"@id":"https:\/\/www.civiltalaica.it\/cms\/lettera-aperta-a-giuliano-ferrara\/"},"author":{"name":"civiltalaica","@id":"https:\/\/www.civiltalaica.it\/cms\/#\/schema\/person\/128c47163e4fe358041e5b6d4de101ff"},"headline":"Lettera aperta a Giuliano Ferrara&#8230;","datePublished":"2008-02-23T11:02:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.civiltalaica.it\/cms\/lettera-aperta-a-giuliano-ferrara\/"},"wordCount":897,"keywords":["aborto","anita pallara","giuliano ferrara","laicismo","laicit\u00e0","laico","sclerosi laterale amiotrofica","sla","sma"],"articleSection":["blog"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.civiltalaica.it\/cms\/lettera-aperta-a-giuliano-ferrara\/","url":"https:\/\/www.civiltalaica.it\/cms\/lettera-aperta-a-giuliano-ferrara\/","name":"Lettera aperta a Giuliano Ferrara... - Associazione Culturale Civilt\u00e0 Laica","isPartOf":{"@id":"https:\/\/www.civiltalaica.it\/cms\/#website"},"datePublished":"2008-02-23T11:02:00+00:00","author":{"@id":"https:\/\/www.civiltalaica.it\/cms\/#\/schema\/person\/128c47163e4fe358041e5b6d4de101ff"},"breadcrumb":{"@id":"https:\/\/www.civiltalaica.it\/cms\/lettera-aperta-a-giuliano-ferrara\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.civiltalaica.it\/cms\/lettera-aperta-a-giuliano-ferrara\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.civiltalaica.it\/cms\/lettera-aperta-a-giuliano-ferrara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.civiltalaica.it\/cms\/"},{"@type":"ListItem","position":2,"name":"Lettera aperta a Giuliano Ferrara&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.civiltalaica.it\/cms\/#website","url":"https:\/\/www.civiltalaica.it\/cms\/","name":"Associazione Culturale Civilt\u00e0 Laica","description":"Per un movimento culturale volto a difendere la Laicit\u00e0 dello Stato.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.civiltalaica.it\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.civiltalaica.it\/cms\/#\/schema\/person\/128c47163e4fe358041e5b6d4de101ff","name":"civiltalaica","url":"https:\/\/www.civiltalaica.it\/cms\/author\/civiltalaica\/"}]}},"_links":{"self":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts\/9278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/comments?post=9278"}],"version-history":[{"count":0,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts\/9278\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/media?parent=9278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/categories?post=9278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/tags?post=9278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}