{"id":318,"date":"2005-04-10T22:36:26","date_gmt":"2005-04-10T22:36:26","guid":{"rendered":""},"modified":"2011-01-26T10:15:08","modified_gmt":"2011-01-26T10:15:08","slug":"sostiene-pera","status":"publish","type":"post","link":"https:\/\/www.civiltalaica.it\/cms\/sostiene-pera\/","title":{"rendered":"Sostiene Pera"},"content":{"rendered":"<p>1) Come \u00e8 ampiamente noto, il Presidente del Senato Marcello Pera, il 21 agosto 2005, ha assolto il, sicuramente per Lui grato, compito di aprire il Meeting dell&#39;Amicizia di Rimini con un discorso da par suo, coniugando sapientemente la forbitezza (l&#39;eleganza) dell&#39;eloquio (del modo di parlare) con la profondit\u00e0 della riflessione, che gi\u00e0 il titolo imponeva e meritava: &quot;Democrazia \u00e8 libert\u00e0? In difesa dell&#39;Occidente&quot;<\/p>\n<p><!--more--><br \/>2) Ora, non essendo n\u00e9 possibile n\u00e9 giusto, tacere di fronte all&#39;ennesima manifestazione di supponenza (arroganza) culturale, non esente, peraltro, da reale e\/o strumentale non sufficiente conoscenza degli argomenti trattati, metteremo per iscritto quelle domande che la lettura integrale del testo ha suscitato in noi.<br \/>Siamo, tra l&#39;altro, sicuri che se mai il Presidente del Senato venisse a conoscenza di queste domande e non avesse compiti ben pi\u00f9 gravi da assolvere, sarebbe in grado sia di fornirci delle esaurienti e rassicuranti risposte, sia di &quot;illuminarci d&#39;immenso&quot;.<br \/>Abbiamo scelto questo metodo, non solo perch\u00e8 lo stesso Marcello Pera inizia ponendosi tre domande, (e, quindi, forse, per una sia pure inconscia volont\u00e0 di imitazione di siffatta Autorit\u00e0 accademica e statale), ma anche per altri due motivi:<br \/>&#8211; vogliamo evitare che si dica che ci si accanisce su singole frasi, estrapolandole dal contesto;<br \/>&#8211; non sarebbe possibile, in questa sede, commentare come meriterebbe un discorso lungo 9 pagine, anche perch\u00e8 si tedierebbe il lettore incautamente avventuratosi nel sito di CIVILT\u00c0 LAICA.<\/p>\n<p><a href=\"..\/..\/..\/documenti\/bruschini\/sostiene_pera.rtf\" target=\"_blank\">File in formato rtf<\/a>&#160;(41 KB), leggibile con Word o con <a href=\"http:\/\/it.openoffice.org\/doc\/utenti\/guide.html\" target=\"_blank\">Write<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1) Come \u00e8 ampiamente noto, il Presidente del Senato Marcello Pera, il 21 agosto 2005, ha assolto il, sicuramente per Lui grato, compito di aprire il Meeting dell&#39;Amicizia di Rimini con un discorso da par suo, coniugando sapientemente la forbitezza (l&#39;eleganza) dell&#39;eloquio (del modo di parlare) con la profondit\u00e0 della riflessione, che gi\u00e0 il titolo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[238],"tags":[24],"class_list":["post-318","post","type-post","status-publish","format-standard","hentry","category-articoli","tag-storia-e-attualita-v-bruschini"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sostiene Pera - Associazione Culturale Civilt\u00e0 Laica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.civiltalaica.it\/cms\/sostiene-pera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sostiene Pera - Associazione Culturale Civilt\u00e0 Laica\" \/>\n<meta property=\"og:description\" content=\"1) Come \u00e8 ampiamente noto, il Presidente del Senato Marcello Pera, il 21 agosto 2005, ha assolto il, sicuramente per Lui grato, compito di aprire il Meeting dell&#039;Amicizia di Rimini con un discorso da par suo, coniugando sapientemente la forbitezza (l&#039;eleganza) dell&#039;eloquio (del modo di parlare) con la profondit\u00e0 della riflessione, che gi\u00e0 il titolo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.civiltalaica.it\/cms\/sostiene-pera\/\" \/>\n<meta property=\"og:site_name\" content=\"Associazione Culturale Civilt\u00e0 Laica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/civiltalaica\" \/>\n<meta property=\"article:published_time\" content=\"2005-04-10T22:36:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-01-26T10:15:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2017\/06\/logo-cl.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"cladmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cladmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/sostiene-pera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/sostiene-pera\\\/\"},\"author\":{\"name\":\"cladmin\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#\\\/schema\\\/person\\\/500a52762e2620e007d6333aa121f5e5\"},\"headline\":\"Sostiene Pera\",\"datePublished\":\"2005-04-10T22:36:26+00:00\",\"dateModified\":\"2011-01-26T10:15:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/sostiene-pera\\\/\"},\"wordCount\":250,\"keywords\":[\"Storia e attualit\u00e0 (V. Bruschini)\"],\"articleSection\":[\"articoli\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/sostiene-pera\\\/\",\"url\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/sostiene-pera\\\/\",\"name\":\"Sostiene Pera - Associazione Culturale Civilt\u00e0 Laica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#website\"},\"datePublished\":\"2005-04-10T22:36:26+00:00\",\"dateModified\":\"2011-01-26T10:15:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#\\\/schema\\\/person\\\/500a52762e2620e007d6333aa121f5e5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/sostiene-pera\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/sostiene-pera\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/sostiene-pera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incontro ad Attigliano (Tr)\",\"item\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/incontro-ad-attigliano-tr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sostiene Pera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/\",\"name\":\"Associazione Culturale Civilt\u00e0 Laica\",\"description\":\"Per un movimento culturale volto a difendere la Laicit\u00e0 dello Stato.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#\\\/schema\\\/person\\\/500a52762e2620e007d6333aa121f5e5\",\"name\":\"cladmin\",\"url\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/author\\\/cladmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sostiene Pera - Associazione Culturale Civilt\u00e0 Laica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.civiltalaica.it\/cms\/sostiene-pera\/","og_locale":"it_IT","og_type":"article","og_title":"Sostiene Pera - Associazione Culturale Civilt\u00e0 Laica","og_description":"1) Come \u00e8 ampiamente noto, il Presidente del Senato Marcello Pera, il 21 agosto 2005, ha assolto il, sicuramente per Lui grato, compito di aprire il Meeting dell&#39;Amicizia di Rimini con un discorso da par suo, coniugando sapientemente la forbitezza (l&#39;eleganza) dell&#39;eloquio (del modo di parlare) con la profondit\u00e0 della riflessione, che gi\u00e0 il titolo [&hellip;]","og_url":"https:\/\/www.civiltalaica.it\/cms\/sostiene-pera\/","og_site_name":"Associazione Culturale Civilt\u00e0 Laica","article_publisher":"https:\/\/www.facebook.com\/civiltalaica","article_published_time":"2005-04-10T22:36:26+00:00","article_modified_time":"2011-01-26T10:15:08+00:00","og_image":[{"width":400,"height":180,"url":"https:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2017\/06\/logo-cl.png","type":"image\/png"}],"author":"cladmin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"cladmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.civiltalaica.it\/cms\/sostiene-pera\/#article","isPartOf":{"@id":"https:\/\/www.civiltalaica.it\/cms\/sostiene-pera\/"},"author":{"name":"cladmin","@id":"https:\/\/www.civiltalaica.it\/cms\/#\/schema\/person\/500a52762e2620e007d6333aa121f5e5"},"headline":"Sostiene Pera","datePublished":"2005-04-10T22:36:26+00:00","dateModified":"2011-01-26T10:15:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.civiltalaica.it\/cms\/sostiene-pera\/"},"wordCount":250,"keywords":["Storia e attualit\u00e0 (V. Bruschini)"],"articleSection":["articoli"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.civiltalaica.it\/cms\/sostiene-pera\/","url":"https:\/\/www.civiltalaica.it\/cms\/sostiene-pera\/","name":"Sostiene Pera - Associazione Culturale Civilt\u00e0 Laica","isPartOf":{"@id":"https:\/\/www.civiltalaica.it\/cms\/#website"},"datePublished":"2005-04-10T22:36:26+00:00","dateModified":"2011-01-26T10:15:08+00:00","author":{"@id":"https:\/\/www.civiltalaica.it\/cms\/#\/schema\/person\/500a52762e2620e007d6333aa121f5e5"},"breadcrumb":{"@id":"https:\/\/www.civiltalaica.it\/cms\/sostiene-pera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.civiltalaica.it\/cms\/sostiene-pera\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.civiltalaica.it\/cms\/sostiene-pera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.civiltalaica.it\/cms\/"},{"@type":"ListItem","position":2,"name":"Incontro ad Attigliano (Tr)","item":"https:\/\/www.civiltalaica.it\/cms\/incontro-ad-attigliano-tr\/"},{"@type":"ListItem","position":3,"name":"Sostiene Pera"}]},{"@type":"WebSite","@id":"https:\/\/www.civiltalaica.it\/cms\/#website","url":"https:\/\/www.civiltalaica.it\/cms\/","name":"Associazione Culturale Civilt\u00e0 Laica","description":"Per un movimento culturale volto a difendere la Laicit\u00e0 dello Stato.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.civiltalaica.it\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.civiltalaica.it\/cms\/#\/schema\/person\/500a52762e2620e007d6333aa121f5e5","name":"cladmin","url":"https:\/\/www.civiltalaica.it\/cms\/author\/cladmin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts\/318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/comments?post=318"}],"version-history":[{"count":0,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts\/318\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/media?parent=318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/categories?post=318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/tags?post=318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}