{"id":16329,"date":"2019-09-20T09:08:34","date_gmt":"2019-09-20T09:08:34","guid":{"rendered":"http:\/\/www.civiltalaica.it\/cms\/?p=16329"},"modified":"2019-09-20T09:08:34","modified_gmt":"2019-09-20T09:08:34","slug":"ansia-news","status":"publish","type":"post","link":"https:\/\/www.civiltalaica.it\/cms\/ansia-news\/","title":{"rendered":"ANSIA NEWS"},"content":{"rendered":"<p><a href=\"http:\/\/www.civiltalaica.it\/cms\/index.php\/ansia-news.html\/pope-facepalm\" rel=\"attachment wp-att-16330\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-16330\" src=\"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2019\/09\/pope-facepalm.jpg\" alt=\"\" width=\"600\" height=\"400\" \/><\/a><\/p>\n<p>POLITICA &#8211; Renzi lascia il PD. Ovviamente il fatto che il giorno dopo erano pronti i sondaggi su quanti punti percentuali la sua scissione avesse fatto perdere il Pd, che da tre giorni non c&#8217;\u00e8 un solo giornale che non titola a quattro colonne quanto sia fondamentale nei nuovi equilibri politici, che sia apparso su quattro trasmissioni in diretta in contemporanea \u00e8 totalmente frutto della casualit\u00e0. Cos\u00ec per lo meno afferma la<span class=\"text_exposed_show\">\u00a0fondazione Licio Gelli.<\/span><\/p>\n<div class=\"text_exposed_show\">\n<p>POLITICA &#8211; In Umbria suona l&#8217;allarme sondaggi. La coalizione PD- 5stelle potrebbe anche battere la destra, Il PD tranquillizza tutti: &#8220;da qui alla fine di ottobre qualche cazzata la faremo sicuro, tranquilli&#8221;.<\/p>\n<p>SOCIETA&#8217; &#8211; Il\u00a0<a class=\"profileLink\" href=\"https:\/\/www.facebook.com\/TerniHorrorFest\/?__tn__=%2CdK-R-R&amp;eid=ARCJk5Jjl3WHjV3JsVinUlcapNJ4jTotb8UbC6brP1qiD-1TsFk2TjPPcqf4X2onXjuEBX1ytLWpPDSs&amp;fref=mentions\" data-hovercard=\"\/ajax\/hovercard\/page.php?id=1210359088995759&amp;extragetparams=%7B%22__tn__%22%3A%22%2CdK-R-R%22%2C%22eid%22%3A%22ARCJk5Jjl3WHjV3JsVinUlcapNJ4jTotb8UbC6brP1qiD-1TsFk2TjPPcqf4X2onXjuEBX1ytLWpPDSs%22%2C%22fref%22%3A%22mentions%22%7D\" data-hovercard-prefer-more-content-show=\"1\">TERNI Horror FEST<\/a>\u00a0dichiara di non aver nulla a che fare con i morti viventi gi\u00e0 apparsi su vari manifesti elettorali in vista delle elezioni regionali.<\/p>\n<p>SPORT &#8211; arrestati i capi della curva ultras juventina. Ricattavano la societ\u00e0 per la gestione del tifo organizzato. Per la formazione schierata l&#8217;anno scorso contro l&#8217;Ajax, invece sembravano avere un alibi.<\/p>\n<p>STORIA: Ricorre il XX settembre. Ed \u00e8 l&#8217;undicesimo anniversario di quando Alemanno a Roma invece dei Bersaglieri celebr\u00f2 i Zuavi pontifici.<\/p>\n<p>POLITICA &#8211; La Lega Nord torna alle origini e fa un bel raduno a Pontida contro i terroni, gli ebrei e i negri. Poi Salvini chiude la giornata con una bambina di Bibbiano sul palco tanto per far capire che tipo \u00e8.<br \/>\nCome dite? Questa \u00e8 una notizia vera che non fa ridere? Ma guardate che non li hanno arrestati mica, sono a piede libero.<span class=\"text_exposed_show\"><br \/>\nBuona questa eh?<\/span><\/p>\n<div class=\"text_exposed_show\">\n<p>SOCIETA&#8217;: oggi debutta &#8220;Il Nord&#8221; quotidiano leghista. Ora bisogna solo trovare i leghisti che sanno leggere.<\/p>\n<p>RICORRENZE: Il 15 settembre, ricorrevano i 25 anni dalla scomparsa Moana Pozzi. Giusto ricordare in questi giorni anche gli 850 miliardi di spermatozoi morti in suo nome.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>POLITICA &#8211; Renzi lascia il PD. Ovviamente il fatto che il giorno dopo erano pronti i sondaggi su quanti punti percentuali la sua scissione avesse fatto perdere il Pd, che da tre giorni non c&#8217;\u00e8 un solo giornale che non titola a quattro colonne quanto sia fondamentale nei nuovi equilibri politici, che sia apparso su [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[238,228],"tags":[1638,165],"class_list":["post-16329","post","type-post","status-publish","format-standard","hentry","category-articoli","category-blog","tag-ansia-news","tag-satira"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ANSIA NEWS - Associazione Culturale Civilt\u00e0 Laica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.civiltalaica.it\/cms\/ansia-news\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ANSIA NEWS - Associazione Culturale Civilt\u00e0 Laica\" \/>\n<meta property=\"og:description\" content=\"POLITICA &#8211; Renzi lascia il PD. Ovviamente il fatto che il giorno dopo erano pronti i sondaggi su quanti punti percentuali la sua scissione avesse fatto perdere il Pd, che da tre giorni non c&#8217;\u00e8 un solo giornale che non titola a quattro colonne quanto sia fondamentale nei nuovi equilibri politici, che sia apparso su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.civiltalaica.it\/cms\/ansia-news\/\" \/>\n<meta property=\"og:site_name\" content=\"Associazione Culturale Civilt\u00e0 Laica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/civiltalaica\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-20T09:08:34+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2019\/09\/pope-facepalm.jpg\" \/>\n<meta name=\"author\" content=\"alexjc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"alexjc\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/ansia-news\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/ansia-news\\\/\"},\"author\":{\"name\":\"alexjc\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#\\\/schema\\\/person\\\/4efef56f866329a1e0943eb27336df1d\"},\"headline\":\"ANSIA NEWS\",\"datePublished\":\"2019-09-20T09:08:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/ansia-news\\\/\"},\"wordCount\":298,\"image\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/ansia-news\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.civiltalaica.it\\\/cms\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/pope-facepalm.jpg\",\"keywords\":[\"ansia news\",\"satira\"],\"articleSection\":[\"articoli\",\"blog\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/ansia-news\\\/\",\"url\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/ansia-news\\\/\",\"name\":\"ANSIA NEWS - Associazione Culturale Civilt\u00e0 Laica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/ansia-news\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/ansia-news\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.civiltalaica.it\\\/cms\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/pope-facepalm.jpg\",\"datePublished\":\"2019-09-20T09:08:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#\\\/schema\\\/person\\\/4efef56f866329a1e0943eb27336df1d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/ansia-news\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/ansia-news\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/ansia-news\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.civiltalaica.it\\\/cms\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/pope-facepalm.jpg\",\"contentUrl\":\"http:\\\/\\\/www.civiltalaica.it\\\/cms\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/pope-facepalm.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/ansia-news\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ANSIA NEWS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/\",\"name\":\"Associazione Culturale Civilt\u00e0 Laica\",\"description\":\"Per un movimento culturale volto a difendere la Laicit\u00e0 dello Stato.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#\\\/schema\\\/person\\\/4efef56f866329a1e0943eb27336df1d\",\"name\":\"alexjc\",\"url\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/author\\\/alexjc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ANSIA NEWS - Associazione Culturale Civilt\u00e0 Laica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.civiltalaica.it\/cms\/ansia-news\/","og_locale":"it_IT","og_type":"article","og_title":"ANSIA NEWS - Associazione Culturale Civilt\u00e0 Laica","og_description":"POLITICA &#8211; Renzi lascia il PD. Ovviamente il fatto che il giorno dopo erano pronti i sondaggi su quanti punti percentuali la sua scissione avesse fatto perdere il Pd, che da tre giorni non c&#8217;\u00e8 un solo giornale che non titola a quattro colonne quanto sia fondamentale nei nuovi equilibri politici, che sia apparso su [&hellip;]","og_url":"https:\/\/www.civiltalaica.it\/cms\/ansia-news\/","og_site_name":"Associazione Culturale Civilt\u00e0 Laica","article_publisher":"https:\/\/www.facebook.com\/civiltalaica","article_published_time":"2019-09-20T09:08:34+00:00","og_image":[{"url":"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2019\/09\/pope-facepalm.jpg","type":"","width":"","height":""}],"author":"alexjc","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"alexjc","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.civiltalaica.it\/cms\/ansia-news\/#article","isPartOf":{"@id":"https:\/\/www.civiltalaica.it\/cms\/ansia-news\/"},"author":{"name":"alexjc","@id":"https:\/\/www.civiltalaica.it\/cms\/#\/schema\/person\/4efef56f866329a1e0943eb27336df1d"},"headline":"ANSIA NEWS","datePublished":"2019-09-20T09:08:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.civiltalaica.it\/cms\/ansia-news\/"},"wordCount":298,"image":{"@id":"https:\/\/www.civiltalaica.it\/cms\/ansia-news\/#primaryimage"},"thumbnailUrl":"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2019\/09\/pope-facepalm.jpg","keywords":["ansia news","satira"],"articleSection":["articoli","blog"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.civiltalaica.it\/cms\/ansia-news\/","url":"https:\/\/www.civiltalaica.it\/cms\/ansia-news\/","name":"ANSIA NEWS - Associazione Culturale Civilt\u00e0 Laica","isPartOf":{"@id":"https:\/\/www.civiltalaica.it\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.civiltalaica.it\/cms\/ansia-news\/#primaryimage"},"image":{"@id":"https:\/\/www.civiltalaica.it\/cms\/ansia-news\/#primaryimage"},"thumbnailUrl":"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2019\/09\/pope-facepalm.jpg","datePublished":"2019-09-20T09:08:34+00:00","author":{"@id":"https:\/\/www.civiltalaica.it\/cms\/#\/schema\/person\/4efef56f866329a1e0943eb27336df1d"},"breadcrumb":{"@id":"https:\/\/www.civiltalaica.it\/cms\/ansia-news\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.civiltalaica.it\/cms\/ansia-news\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.civiltalaica.it\/cms\/ansia-news\/#primaryimage","url":"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2019\/09\/pope-facepalm.jpg","contentUrl":"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2019\/09\/pope-facepalm.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.civiltalaica.it\/cms\/ansia-news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.civiltalaica.it\/cms\/"},{"@type":"ListItem","position":2,"name":"ANSIA NEWS"}]},{"@type":"WebSite","@id":"https:\/\/www.civiltalaica.it\/cms\/#website","url":"https:\/\/www.civiltalaica.it\/cms\/","name":"Associazione Culturale Civilt\u00e0 Laica","description":"Per un movimento culturale volto a difendere la Laicit\u00e0 dello Stato.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.civiltalaica.it\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.civiltalaica.it\/cms\/#\/schema\/person\/4efef56f866329a1e0943eb27336df1d","name":"alexjc","url":"https:\/\/www.civiltalaica.it\/cms\/author\/alexjc\/"}]}},"_links":{"self":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts\/16329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/comments?post=16329"}],"version-history":[{"count":2,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts\/16329\/revisions"}],"predecessor-version":[{"id":16332,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts\/16329\/revisions\/16332"}],"wp:attachment":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/media?parent=16329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/categories?post=16329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/tags?post=16329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}