{"id":12674,"date":"2014-10-25T00:23:14","date_gmt":"2014-10-25T00:23:14","guid":{"rendered":"http:\/\/www.civiltalaica.it\/cms\/?p=12674"},"modified":"2014-10-25T00:23:14","modified_gmt":"2014-10-25T00:23:14","slug":"due-fazioni-una-contro-laltra-armate","status":"publish","type":"post","link":"https:\/\/www.civiltalaica.it\/cms\/due-fazioni-una-contro-laltra-armate\/","title":{"rendered":"Due fazioni una contro l&#8217;altra armate?"},"content":{"rendered":"<p>Ho sentito pi\u00f9 volte un bravo giornalista scientifico dire che uno dei motivi per i quali il suo lavoro \u00e8 difficile \u00e8 che gli chiedono sempre di presentare la notizia sotto la forma delle \u201cdue campane\u201d: uno scienziato dice una cosa e un altro ne dice un\u2019altra. Chiaro l\u2019imbarazzo del giornalista ad adeguarsi a una formula simile nei molti casi nei quali \u00e8 evidente che una delle due campane ha posizioni faziose e insostenibili. \u00c8 possibile che persino Nature sia cascata nella trappola delle due campane? <!--more--><a href=\"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2014\/10\/unnamed.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-12675\" src=\"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2014\/10\/unnamed.jpg\" alt=\"unnamed\" width=\"271\" height=\"186\" \/><\/a>Un articolo pubblicato sul numero del 7 ottobre scorso sembra proprio seguire questa strada: alcuni dei maggiori esponenti dell\u2019evoluzionismo contemporaneo sono stati raggruppati in due fazioni, ognuna delle quali ha esposto le sue posizioni. Naturalmente, se il lettore ha la pazienza di leggere l\u2019articolo, alla fine scoprir\u00e0 che le due posizioni non sono affatto monolitiche, al punto che, addirittura, non \u00e8 facile individuarle e definirle. I due gruppi di scienziati firmano assieme l\u2019articolo, ma le loro posizioni sono mostrate su due colonne separate, ad affrontarsi l\u2019un l\u2019altra. La materia del contendere? La sopravvivenza o la morte della Sintesi Moderna.<\/p>\n<p>Per capire le radici del dibattito, occorre fare un passo indietro, fino agli anni \u201940 del secolo scorso, nei quali si \u00e8 definita quella che sar\u00e0 chiamata, a partire dal titolo di un libro di Julian Huxley, la Sintesi Moderna. La Sintesi Moderna nasce come una reazione alle posizioni apertamente antidarwiniane che si consolidarono all\u2019inizio del \u2018900 attorno alla genetica nascente, etichettate con il nome di \u201cmutazionismo\u201d: contrariamente al cuore del messaggio darwiniano (il meccanismo principale del cambiamento \u00e8 la presenza nelle popolazioni di una grande quantit\u00e0 di minuta variabilit\u00e0 casuale, continuamente vagliata dalla selezione naturale) i mutazionisti \u2013 e con loro quasi tutti i \u201cpadri\u201d della genetica nascente \u2013 affermavano la preminenza di grandi e \u201cimprovvisi\u201d cambiamenti genetici (da essi appunto denominati \u201cmutazioni\u201d) relegando il ruolo della selezione naturale a semplice vaglio delle nuove specie cos\u00ec formate. Le piccole variazioni presenti ovunque nelle popolazioni, delle quali parlava Darwin, erano da essi definite \u201cfluttuazioni\u201d. A partire dagli anni \u201820 del \u2018900 si comprese meglio la natura genetica della variabilit\u00e0 popolazionale e delle mutazioni, e pian piano il nocciolo del pensiero darwiniano torn\u00f2 in auge, tanto da spingere alcuni personaggi eminenti dell\u2019evoluzionismo a costruire attorno ad esso, appunto, la Sintesi Moderna. Ma, come era ampiamente prevedibile, l\u2019accordo sui punti fondanti dell\u2019evoluzionismo moderno \u2013 il prevalere di piccoli cambiamenti e della selezione naturale come fattori dell\u2019evoluzione &#8211; fu di breve durata, e poco dopo le strade dei diversissimi scienziati che l\u2019avevano costruita (zoologi, botanici, paleontologi, citologi, genetisti di popolazione \u2026) ricominciarono a divergere. E a partire dagli anni \u201960 del \u2018900 iniziarono le \u201ceresie\u201d, dalla teoria neutrale dell\u2019evoluzione molecolare agli equilibri punteggiati, dalla costruzione della nicchia alla biologia evoluzionistica dello sviluppo, dall\u2019eredit\u00e0 epigenetica all\u2019assimilazione genetica \u2026 fino a quando qualcuno cominci\u00f2 a chiedersi se non fosse arrivato il momento di costruire una nuova \u201cSintesi Estesa\u201d sopra al, per cos\u00ec dire, cadavere della Sintesi Moderna.<\/p>\n<p>E\u2019 su questa base che si innesta l\u2019operazione culturale di Nature, che ha riunito un gruppo di ricercatori favorevoli alla Sintesi Estesa e l\u2019altro contrario. I due gruppi sono stati chiamati dai sostenitori della Sintesi Estesa con gli acronimi EES (Extended Evolutionary Sinthesis) e SET (Standard Evolutionary Theory) che useremo qui per brevit\u00e0. Nature ha chiesto ai due schieramenti di esporre le diverse posizioni, e ha intitolato l\u2019articolo, nel suo complesso, La teoria evoluzionistica ha bisogno di un ripensamento?<\/p>\n<p>I sostenitori della EES intitolano il loro intervento Yes, urgently, s\u00ec, urgentemente, e basano la loro posizione sul fatto che la teoria attuale (SET) fa affidamento soltanto sui geni ed \u00e8 concentrata sui processi che ne alterano le frequenze (vedi specchietto); al contrario, agenti importanti dell\u2019evoluzione che non possono essere ridotti ai geni devono essere incorporati nella struttura profonda della teoria evoluzionistica darwiniana. Ad esempio: gli organismi sono generati attraverso un processo di sviluppo complesso e sottoposto a molti diversi fattori, non sono cio\u00e8 semplicemente \u201cprogrammati\u201d dai geni. La biologia evoluzionistica dello sviluppo (EvoDevo in gergo) ha messo in luce che molte variazioni che alterano lo sviluppo (e quindi il suo risultato finale, l\u2019organismo adulto) non sono casuali, come esemplificato da un gruppo di centopiedi dove pi\u00f9 di mille specie diverse hanno un numero dispari di segmenti a causa del loro meccanismo di sviluppo. I pesci ciclidi dei laghi Malawi e Tanganica formano ciascuno un gruppo monofiletico con centinaia di specie, ma le forme che le diverse specie assumono si ripetono nei due laghi in modo impressionante. Convergenza, dice la SET. Rispondono i sostenitori della EES: ma quante coincidenze dobbiamo chiamare in causa? Non sarebbe pi\u00f9 parsimonioso immaginare che modelli di sviluppo orientati, assieme alla selezione naturale, guidino la formazione delle nuove specie? Un altro tipo di sviluppo orientato accade in seguito ad un fenomeno ben noto, chiamato plasticit\u00e0 dello sviluppo, ossia il fatto che individui dotati dello stesso corredo genetico possono dare luogo a fenotipi diversi, a volte diversissimi, se sviluppatisi in ambienti diversi. In tal caso, un intervento della selezione successivo alla produzione di varianti fenotipiche, potrebbe, dato un tempo sufficiente, \u201cfissare\u201d fenotipi diversi generando speciazione: in tali casi il cambiamento genetico segue, piuttosto che precedere, l\u2019evoluzione. \u00c8 questo il fenomeno dell\u2019assimilazione genetica, noto fin dagli anni \u201950 del \u2018900. Abbastanza simile a questo meccanismo \u00e8 la \u201cspeciazione ecologica\u201d, quel fenomeno per il quale popolazioni dotate di plasticit\u00e0 fenotipica sviluppano fenotipi diversi in ambienti diversi, ma identici in ambienti ecologicamente simili, anche se geograficamente lontani. Negli spinarelli (Gasterosteus aculeatus) si \u00e8 verificata interfecondit\u00e0 maggiore fra \u201cpopolazioni\u201d ecologicamente simili ma geograficamente separate che non fra popolazioni ecologicamente diverse che vivono nel medesimo lago.<\/p>\n<p>Un altro tema caro ai sostenitori della EES \u00e8 quello della relazione fra organismi e ambiente. C\u2019\u00e8 una bella differenza fra l\u2019adattamento che consente alle termiti di costruire i loro nidi e un\u2019eruzione vulcanica, dicono gli autori; un\u2019eruzione vulcanica \u00e8 un fenomeno a s\u00e9 stante, indipendente dalla vita degli organismi, mentre la costruzione dei termitai \u00e8 legata alla biologia di un gruppo di viventi, che con il loro lavoro modificano l\u2019ambiente, e quindi la nicchia ecologica delle generazioni successive. \u00c8 la teoria della \u201ccostruzione della nicchia\u201d. L\u2019ambiente dunque non \u201cgiudica\u201d le varianti genetiche prodotte a caso, ma viene, almeno in parte, continuamente costruito e modificato dai viventi. Ma non \u00e8 solo un ambiente modificato che una generazione lascia alla successiva come un\u2019eredit\u00e0 non-genetica. Vi \u00e8 pure un\u2019eredit\u00e0 epigenetica &#8211; che non passa attraverso il DNA, all\u2019interno delle cellule. L\u2019azione dei geni pu\u00f2 venire modificata o alterata da molecole che si attaccano al DNA senza modificarne la sequenza. Insomma, nel complesso in questi casi \u201cla variazione non \u00e8 casuale, c\u2019\u00e8 molto pi\u00f9 da ereditare oltre ai geni, e vi sono molte strade per adattare gli organismi all\u2019ambiente\u201d. Naturalmente, i fenomeni descritti sono noti anche alla SET, che per\u00f2 li interpreta altrimenti: ad esempio, i fenomeni di sviluppo orientato sono letti come \u201cvincoli\u201d a ci\u00f2 che la selezione pu\u00f2 fare, ostacoli all\u2019adattamento. Al contrario l\u2019EES vede i processi di sviluppo come elementi creativi dello sviluppo.<\/p>\n<p>L\u2019intervento dei favorevoli alla SET \u00e8 intitolato No, all is well, no va tutto bene. Dopo aver ricostruito brevemente la storia della Sintesi Moderna, essi presentano le scoperte ad essa successive, non come sovvertimento dei suoi fondamenti, ma come sviluppi della sintesi. Ad esempio, la teoria neutrale dell\u2019evoluzione molecolare sarebbe prevedibile se consideriamo tutto lo spettro dei valori della selezione naturale, dai pi\u00f9 negativi ai pi\u00f9 positivi. Nella \u201czona mediana\u201d ci sar\u00e0 posto pure per valori neutrali della selezione! Passano poi a considerare i quattro temi pi\u00f9 sottolineati dai sostenitori della EES: la plasticit\u00e0 fenotipica, la costruzione della nicchia, l\u2019eredit\u00e0 inclusiva e lo sviluppo indirizzato. Naturalmente quei dati sono da essi accettati e considerati, anzi essi affermano di studiare attivamente tali fenomeni, ma di considerarli pi\u00f9 espansioni dell\u2019evoluzionismo &#8211; visto come una disciplina in crescita continua &#8211; che non come eresie in grado di scalzare i fondamenti di una disciplina universalmente accettata grazie all\u2019accumulo ormai irreversibile di prove. I sostenitori della SET aggiungono addirittura altri fenomeni importanti, non considerati a loro dire nella parte dell\u2019articolo scritto dai sostenitori della EES: l\u2019epistasi, il fenomeno che si verifica quando una coppia di alleli copre l\u2019espressione fenotipica di un\u2019altra coppia di alleli; la variazione genetica criptica (mutazioni che si manifestano solo in particolari condizioni ambientali); l\u2019estinzione; l\u2019adattamento al cambiamento climatico\u2026 ma affermano che ogni evoluzionista avrebbe una lunga lista di fenomeni altrettanto degni di attenzione. E aggiungono \u201coppure potremmo rimboccarci le maniche, tornare al lavoro, identificare i fondamenti teorici e costruire uno schema solido sulla base di casi empirici.\u201d<\/p>\n<p>L\u2019atteggiamento che la EES deride come gene-centrico \u00e8 stato il programma pi\u00f9 potentemente predittivo, largamente applicabile, ed empiricamente validato, della teoria evoluzionista. Al contrario, l\u2019importanza della plasticit\u00e0 fenotipica \u00e8 ben nota, ma, afferma la SET, essa ha comunque una base genetica, e le osservazioni e gli esperimenti di Waddington sulla assimilazione genetica sono stati recentemente reinterpretati come dovuti a selezione a carico delle heat shock proteins. Sulle forme di eredit\u00e0 epigenetica essi affermano che non esiste alcun caso provato di un evento evolutivo rilevante che abbia una base solo epigenetica. I quattro fenomeni che i sostenitori della EES pongono alla base della loro critica sono invece da considerarsi come \u201caggiunte\u201d ai processi fondamentali del cambiamento evolutivo: selezione naturale, deriva genetica, mutazione, ricombinazione e flusso genico. \u201cAnche noi &#8211; concludono i sostenitori della SET &#8211; vogliamo una sintesi estesa, ma per noi queste parole sono in minuscolo, perch\u00e9 questo \u00e8 il modo nel quale il nostro campo ha sempre proceduto\u201d.<\/p>\n<p>Mi sembra che una conclusione forte che si pu\u00f2 trarre dalla lettura di questo articolo sia che il limite maggiore all\u2019accettazione generalizzata della proposta della EES sia la mancanza di un nucleo fondante centrale: essa, per ora, \u00e8 pi\u00f9 orientata ad una critica di molti aspetti, anche importanti, della SET, piuttosto che alla proposta di una nuova teoria solida e comprensiva.<\/p>\n<p><strong>Marco Ferraguti &#8211; <a href=\"http:\/\/www.pikaia.eu\/EasyNe2\/Notizie\/Due_fazioni_l%E2%80%99una_contro_l%E2%80%99altra_armate.aspx\">Pikaia<\/a><\/strong><\/p>\n<p>Questo specchietto \u00e8 nei materiali aggiuntivi dell\u2019articolo <br \/>___________________________________________________________________________________________________<br \/>La teoria evoluzionistica standard (SET) \u00e8 gene-centrica, e considera processi evolutivi solo quelli che cambiano le frequenze geniche<\/p>\n<p>Mutazione: introduce nuove varianti a caso. L\u2019occorrenza ripetuta delle stesse varianti geniche si chiama pressione mutazionale<\/p>\n<p>Selezione naturale: rende le varianti adattative pi\u00f9 comuni attraverso sopravvivenza e riproduzione differenziali<\/p>\n<p>Deriva genetica: fluttuazioni casuali nella frequenza delle varianti genetiche causate dal campionamento in piccole popolazioni<\/p>\n<p>Flusso genico: le varianti entrano ed escono da una popolazione per migrazione, dispersione o incrocio<\/p>\n<p>__________________________________________________________________________________________________<br \/>La sintesi estesa (EES) \u00e8 centrata sugli organismi e riconosce altri processi in aggiunta a quelli che cambiano le frequenze geniche<\/p>\n<p>Influenza dello sviluppo: il processo di sviluppo guida le forme degli organismi lungo percorsi particolari<\/p>\n<p>Plasticit\u00e0: nuove forme, potenzialmente funzionali, sono indotte dall\u2019ambiente e successivamente stabilizzate dalla selezione<\/p>\n<p>Costruzione della nicchia: gli organismi modificano sistematicamente le risorse ambientali fino ad influenzare lo sviluppo e l\u2019evoluzione dei discendenti attraverso una modificazioni delle pressioni selettive<\/p>\n<p>Eredit\u00e0 inclusiva: gli organismi ereditano una gran variet\u00e0 di materiali dai loro antenati, inclusi marcatori epigenetici, ormoni, simbionti, conoscenze ed abilit\u00e0 apprese, retaggi ecologici.<br \/>________________________________________________________________________________________________<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ho sentito pi\u00f9 volte un bravo giornalista scientifico dire che uno dei motivi per i quali il suo lavoro \u00e8 difficile \u00e8 che gli chiedono sempre di presentare la notizia sotto la forma delle \u201cdue campane\u201d: uno scienziato dice una cosa e un altro ne dice un\u2019altra. Chiaro l\u2019imbarazzo del giornalista ad adeguarsi a una [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[238,233],"tags":[1373,977,1372,522],"class_list":["post-12674","post","type-post","status-publish","format-standard","hentry","category-articoli","category-filosofia-2","tag-dibattito-sullevoluzione","tag-evoluzionismo","tag-marco-ferraguti","tag-pikaia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Due fazioni una contro l&#039;altra armate? - Associazione Culturale Civilt\u00e0 Laica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.civiltalaica.it\/cms\/due-fazioni-una-contro-laltra-armate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Due fazioni una contro l&#039;altra armate? - Associazione Culturale Civilt\u00e0 Laica\" \/>\n<meta property=\"og:description\" content=\"Ho sentito pi\u00f9 volte un bravo giornalista scientifico dire che uno dei motivi per i quali il suo lavoro \u00e8 difficile \u00e8 che gli chiedono sempre di presentare la notizia sotto la forma delle \u201cdue campane\u201d: uno scienziato dice una cosa e un altro ne dice un\u2019altra. Chiaro l\u2019imbarazzo del giornalista ad adeguarsi a una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.civiltalaica.it\/cms\/due-fazioni-una-contro-laltra-armate\/\" \/>\n<meta property=\"og:site_name\" content=\"Associazione Culturale Civilt\u00e0 Laica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/civiltalaica\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-25T00:23:14+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2014\/10\/unnamed.jpg\" \/>\n<meta name=\"author\" content=\"alexjc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"alexjc\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/due-fazioni-una-contro-laltra-armate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/due-fazioni-una-contro-laltra-armate\\\/\"},\"author\":{\"name\":\"alexjc\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#\\\/schema\\\/person\\\/4efef56f866329a1e0943eb27336df1d\"},\"headline\":\"Due fazioni una contro l&#8217;altra armate?\",\"datePublished\":\"2014-10-25T00:23:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/due-fazioni-una-contro-laltra-armate\\\/\"},\"wordCount\":1855,\"image\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/due-fazioni-una-contro-laltra-armate\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.civiltalaica.it\\\/cms\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/unnamed.jpg\",\"keywords\":[\"dibattito sull'evoluzione\",\"evoluzionismo\",\"marco ferraguti\",\"pikaia\"],\"articleSection\":[\"articoli\",\"filosofia e scienza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/due-fazioni-una-contro-laltra-armate\\\/\",\"url\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/due-fazioni-una-contro-laltra-armate\\\/\",\"name\":\"Due fazioni una contro l'altra armate? - Associazione Culturale Civilt\u00e0 Laica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/due-fazioni-una-contro-laltra-armate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/due-fazioni-una-contro-laltra-armate\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.civiltalaica.it\\\/cms\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/unnamed.jpg\",\"datePublished\":\"2014-10-25T00:23:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#\\\/schema\\\/person\\\/4efef56f866329a1e0943eb27336df1d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/due-fazioni-una-contro-laltra-armate\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/due-fazioni-una-contro-laltra-armate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/due-fazioni-una-contro-laltra-armate\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.civiltalaica.it\\\/cms\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/unnamed.jpg\",\"contentUrl\":\"http:\\\/\\\/www.civiltalaica.it\\\/cms\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/unnamed.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/due-fazioni-una-contro-laltra-armate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Due fazioni una contro l&#8217;altra armate?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/\",\"name\":\"Associazione Culturale Civilt\u00e0 Laica\",\"description\":\"Per un movimento culturale volto a difendere la Laicit\u00e0 dello Stato.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#\\\/schema\\\/person\\\/4efef56f866329a1e0943eb27336df1d\",\"name\":\"alexjc\",\"url\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/author\\\/alexjc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Due fazioni una contro l'altra armate? - Associazione Culturale Civilt\u00e0 Laica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.civiltalaica.it\/cms\/due-fazioni-una-contro-laltra-armate\/","og_locale":"it_IT","og_type":"article","og_title":"Due fazioni una contro l'altra armate? - Associazione Culturale Civilt\u00e0 Laica","og_description":"Ho sentito pi\u00f9 volte un bravo giornalista scientifico dire che uno dei motivi per i quali il suo lavoro \u00e8 difficile \u00e8 che gli chiedono sempre di presentare la notizia sotto la forma delle \u201cdue campane\u201d: uno scienziato dice una cosa e un altro ne dice un\u2019altra. Chiaro l\u2019imbarazzo del giornalista ad adeguarsi a una [&hellip;]","og_url":"https:\/\/www.civiltalaica.it\/cms\/due-fazioni-una-contro-laltra-armate\/","og_site_name":"Associazione Culturale Civilt\u00e0 Laica","article_publisher":"https:\/\/www.facebook.com\/civiltalaica","article_published_time":"2014-10-25T00:23:14+00:00","og_image":[{"url":"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2014\/10\/unnamed.jpg","type":"","width":"","height":""}],"author":"alexjc","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"alexjc","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.civiltalaica.it\/cms\/due-fazioni-una-contro-laltra-armate\/#article","isPartOf":{"@id":"https:\/\/www.civiltalaica.it\/cms\/due-fazioni-una-contro-laltra-armate\/"},"author":{"name":"alexjc","@id":"https:\/\/www.civiltalaica.it\/cms\/#\/schema\/person\/4efef56f866329a1e0943eb27336df1d"},"headline":"Due fazioni una contro l&#8217;altra armate?","datePublished":"2014-10-25T00:23:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.civiltalaica.it\/cms\/due-fazioni-una-contro-laltra-armate\/"},"wordCount":1855,"image":{"@id":"https:\/\/www.civiltalaica.it\/cms\/due-fazioni-una-contro-laltra-armate\/#primaryimage"},"thumbnailUrl":"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2014\/10\/unnamed.jpg","keywords":["dibattito sull'evoluzione","evoluzionismo","marco ferraguti","pikaia"],"articleSection":["articoli","filosofia e scienza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.civiltalaica.it\/cms\/due-fazioni-una-contro-laltra-armate\/","url":"https:\/\/www.civiltalaica.it\/cms\/due-fazioni-una-contro-laltra-armate\/","name":"Due fazioni una contro l'altra armate? - Associazione Culturale Civilt\u00e0 Laica","isPartOf":{"@id":"https:\/\/www.civiltalaica.it\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.civiltalaica.it\/cms\/due-fazioni-una-contro-laltra-armate\/#primaryimage"},"image":{"@id":"https:\/\/www.civiltalaica.it\/cms\/due-fazioni-una-contro-laltra-armate\/#primaryimage"},"thumbnailUrl":"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2014\/10\/unnamed.jpg","datePublished":"2014-10-25T00:23:14+00:00","author":{"@id":"https:\/\/www.civiltalaica.it\/cms\/#\/schema\/person\/4efef56f866329a1e0943eb27336df1d"},"breadcrumb":{"@id":"https:\/\/www.civiltalaica.it\/cms\/due-fazioni-una-contro-laltra-armate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.civiltalaica.it\/cms\/due-fazioni-una-contro-laltra-armate\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.civiltalaica.it\/cms\/due-fazioni-una-contro-laltra-armate\/#primaryimage","url":"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2014\/10\/unnamed.jpg","contentUrl":"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2014\/10\/unnamed.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.civiltalaica.it\/cms\/due-fazioni-una-contro-laltra-armate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.civiltalaica.it\/cms\/"},{"@type":"ListItem","position":2,"name":"Due fazioni una contro l&#8217;altra armate?"}]},{"@type":"WebSite","@id":"https:\/\/www.civiltalaica.it\/cms\/#website","url":"https:\/\/www.civiltalaica.it\/cms\/","name":"Associazione Culturale Civilt\u00e0 Laica","description":"Per un movimento culturale volto a difendere la Laicit\u00e0 dello Stato.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.civiltalaica.it\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.civiltalaica.it\/cms\/#\/schema\/person\/4efef56f866329a1e0943eb27336df1d","name":"alexjc","url":"https:\/\/www.civiltalaica.it\/cms\/author\/alexjc\/"}]}},"_links":{"self":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts\/12674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/comments?post=12674"}],"version-history":[{"count":0,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts\/12674\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/media?parent=12674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/categories?post=12674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/tags?post=12674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}