{"id":12315,"date":"2014-05-03T14:01:57","date_gmt":"2014-05-03T14:01:57","guid":{"rendered":"http:\/\/www.civiltalaica.it\/cms\/?p=12315"},"modified":"2014-05-03T14:24:55","modified_gmt":"2014-05-03T14:24:55","slug":"evviva-wojtyla-santo","status":"publish","type":"post","link":"https:\/\/www.civiltalaica.it\/cms\/evviva-wojtyla-santo\/","title":{"rendered":"Evviva Wojtyla santo!"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p align=\"JUSTIFY\">L\u2019incidente che il 24 aprile, a Cevo (BS) ha determinato la morte di un povero ragazzo che, a causa di problemi motori, non avrebbe fatto in tempo a scostarsi nella caduta di una grossa croce lignea dedicata all\u2019ex papa polacco, \u00e8 parso a molti un segno del cielo contro la sua santificazione. Ci sarebbe da ridere su queste superstizioni se non fosse stata una tragedia. <!--more--><a href=\"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2014\/05\/witila_pinochet.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-12316\" src=\"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2014\/05\/witila_pinochet-300x219.jpg\" alt=\"witila_pinochet\" width=\"300\" height=\"219\" srcset=\"https:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2014\/05\/witila_pinochet-300x219.jpg 300w, https:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2014\/05\/witila_pinochet.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Nel libro \u201cSpiegare i miracoli\u201d ho chiarito che un miracolo non \u00e8 un fatto ma una interpretazione di un fatto, per lo pi\u00f9 connesso a una applicazione errata del principio di causalit\u00e0, ovvero, \u00e8 la mente del credente che associa un evento di guarigione, che la scienza considera \u201cstraordinario\u201d, perch\u00e9 \u00e8 una guarigione non contro natura ma agli estremi della curva statistica della distribuzione degli eventi (code), a un altro fatto che \u00e8 la invocazione a un santo o alla Madonna oppure a una statua, una fonte d\u2019acqua, a un dio Ind\u00f9 (es. Ganesh) o, come in passato, a totem, alberi, montagne sacre, ecc. Nel libro ho anche spiegato che, a rigore di logica e di applicazione delle leggi di probabilit\u00e0, bisognerebbe computare nel calcolo e nella definizione degli eventi straordinari tutti i \u201cmiracoli mancati\u201d (es. tutti i malati non guariti che pur hanno pregato e invocato la guarigione; oppure i tanti morti sotto un crollo d\u2019edificio o di un incidente aereo o naufragio, rispetto ai pochi sopravvissuti miracolati) e anche gli \u201canti-miracoli\u201d, come potrebbe essere l\u2019incidente di Cevo. Ma questo non accade mai nella mente del fedele e dei cleri (di qualsiasi religione), troppo coinvolti nella ricerca del segno divino, per analizzare criticamente i fenomeni. Un credente mi obiett\u00f2 una volta che le guarigioni miracolose non sono equiparabili a quelle straordinarie, perch\u00e9 \u201cin substantia\u201d cio\u00e8 dal punto di vista anatomico e fisiologico sono identiche, per\u00f2 ci\u00f2 che le differenzia sarebbe l\u2019intervento causale divino: replicai che forse non si accorgeva della crudelt\u00e0 della sua affermazione, avendo io, come medico, assistito alla morte di bambini piccoli e giovani innocenti, cristiani oranti come lui, e che avrebbe dovuto spiegare come Iddio decideva chi miracolare e chi no, e perch\u00e9 anche gli dei zoomorfi di varie religioni operassero tanti miracoli. Ma la diatriba non finirebbe mai, scontrandosi due prospettive opposte, quella fideista e quella critica. Ad ogni modo, la Chiesa di Roma ha deciso per la canonizzazione di Wojtyla, per un paio di miracoli compiuti, nonostante resistenze anche interne. Noi laici, negli anni passati abbiamo denunciato i molti aspetti negativi del pontificato del papa polacco, tra i quali l\u2019uso politico della religione, il silenzio e\/o la semicomplicit\u00e0 su dittatori sanguinari (quella apparizione al fianco di Pinochet!!), gli scandali dello IOR (il papa \u00e8 l\u2019unico sovrano che detiene personalmente i beni economici del suo stato), la copertura della pedofilia nel clero e delle innumerevoli violenze e soprusi morali perpetrate nei collegi e scuole cattoliche (es. le Maddalene in Irlanda) e altro ancora. Ma veniamo all\u2019attualit\u00e0. In tanti si sono domandati: perch\u00e9 santificare insieme Roncalli e Wojtyla? ossia, perch\u00e9 aspettare mezzo secolo per l\u2019uno e pochi anni per l\u2019altro? forse perch\u00e9 a Roncalli non sono stati attribuiti miracoli per molti anni e solo di recente si? questa ipotesi ci pare assai improbabile, poich\u00e9 la Chiesa sa trovare miracoli ovunque, quando servono (si legga il capitolo dedicato alla distribuzione dei miracoli in 150 anni e l\u2019appendice sul 67 miracolo di Lourdes, per avere conferma), inoltre il \u201cpapa buono\u201d \u00e8 sempre stato il pi\u00f9 amato e invocato. E allora? Mi si perdoni la malizia, ma la santificazione dei due papi insieme ricorda tanto il \u201cpaghi uno, prendi due\u201d, ovvero una furbata per soddisfare il popolo che chiedeva la santificazione di Wojtyla, sui quali sussistevano dubbi, e insieme tranquillizzare gli oppositori interni. Non \u00e8 cos\u00ec? Forse, ma intanto si dovrebbe spiegare perch\u00e9 il 27 aprile piazza S. Pietro era bianca e rossa (i colori polacchi) mentre tutti gli altri colori del mondo erano sparute chiazze. Forse penso male, vedremo, ma intanto mi permetto di coniare un nuovo termine, la <i>bergogliata<\/i>, ossia un azione pacata, bonaria, sorridente, ma proprio per questo molto insidiosa per la laicit\u00e0. Confesso che mi stava venendo a piacere molto papa Bergoglio, specie per i suoi sforzi di eliminare gravi aberrazioni della Chiesa, ma mi stavo dimenticando che \u00e8 il pontefice supremo di una istituzione nefanda, mefitica, addirittura con un passato criminale (Deschner, Storia criminale del cristianesimo, Ariele) per la quale sempre pi\u00f9 persone provano repulsione, fastidio, ripugnanza (ma davvero cari cattolici pensate che le mense, i lazzaretti, le varie forme di assistenza che avete posto e ponete in atto possano controbilanciare tutto il male che avete fatto per secoli? pensate davvero che la carit\u00e0 fatta coi soldi e il sudore altrui sia lodevole? pensate che una carezza di un prete possa annullare la sua pedofilia o il sorriso di una suora tutte le vergate e le punizioni distribuite alle educande? Io sono cresciuto nei vostri collegi, io vi conosco!). Poi \u00e8 arrivato il 27 aprile, che senza l\u2019assenso del nuovo papa argentino non avrebbe potuto svolgersi, e cos\u00ec ho di nuovo realizzato che, sar\u00e0 anche buono, bravo, simpatico, retto e giusto, ma papa Bergoglio \u00e8 e resta il capo della cattolicit\u00e0, che per il non credente e i credenti non cristiani \u00e8 una delle peggiori confessioni religiose della storia dell\u2019umanit\u00e0, verso la quale l\u2019opposizione intellettuale e culturale deve essere continua, intransigente, permanente. E allora, viva il 27 aprile, viva Wojtyla santo!<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Maurizio Magnani<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; L\u2019incidente che il 24 aprile, a Cevo (BS) ha determinato la morte di un povero ragazzo che, a causa di problemi motori, non avrebbe fatto in tempo a scostarsi nella caduta di una grossa croce lignea dedicata all\u2019ex papa polacco, \u00e8 parso a molti un segno del cielo contro la sua santificazione. Ci sarebbe [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[238,232],"tags":[134,1333,798,1334],"class_list":["post-12315","post","type-post","status-publish","format-standard","hentry","category-articoli","category-riflessioni-2","tag-giovanni-paolo-ii","tag-karol-woitjla","tag-maurizio-magnani","tag-santificazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evviva Wojtyla santo! - Associazione Culturale Civilt\u00e0 Laica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.civiltalaica.it\/cms\/evviva-wojtyla-santo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evviva Wojtyla santo! - Associazione Culturale Civilt\u00e0 Laica\" \/>\n<meta property=\"og:description\" content=\"&nbsp; L\u2019incidente che il 24 aprile, a Cevo (BS) ha determinato la morte di un povero ragazzo che, a causa di problemi motori, non avrebbe fatto in tempo a scostarsi nella caduta di una grossa croce lignea dedicata all\u2019ex papa polacco, \u00e8 parso a molti un segno del cielo contro la sua santificazione. Ci sarebbe [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.civiltalaica.it\/cms\/evviva-wojtyla-santo\/\" \/>\n<meta property=\"og:site_name\" content=\"Associazione Culturale Civilt\u00e0 Laica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/civiltalaica\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-03T14:01:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-05-03T14:24:55+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2014\/05\/witila_pinochet-300x219.jpg\" \/>\n<meta name=\"author\" content=\"alexjc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"alexjc\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/evviva-wojtyla-santo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/evviva-wojtyla-santo\\\/\"},\"author\":{\"name\":\"alexjc\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#\\\/schema\\\/person\\\/4efef56f866329a1e0943eb27336df1d\"},\"headline\":\"Evviva Wojtyla santo!\",\"datePublished\":\"2014-05-03T14:01:57+00:00\",\"dateModified\":\"2014-05-03T14:24:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/evviva-wojtyla-santo\\\/\"},\"wordCount\":907,\"image\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/evviva-wojtyla-santo\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.civiltalaica.it\\\/cms\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/witila_pinochet-300x219.jpg\",\"keywords\":[\"giovanni paolo ii\",\"karol woitjla\",\"maurizio magnani\",\"santificazioni\"],\"articleSection\":[\"articoli\",\"riflessioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/evviva-wojtyla-santo\\\/\",\"url\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/evviva-wojtyla-santo\\\/\",\"name\":\"Evviva Wojtyla santo! - Associazione Culturale Civilt\u00e0 Laica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/evviva-wojtyla-santo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/evviva-wojtyla-santo\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.civiltalaica.it\\\/cms\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/witila_pinochet-300x219.jpg\",\"datePublished\":\"2014-05-03T14:01:57+00:00\",\"dateModified\":\"2014-05-03T14:24:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#\\\/schema\\\/person\\\/4efef56f866329a1e0943eb27336df1d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/evviva-wojtyla-santo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/evviva-wojtyla-santo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/evviva-wojtyla-santo\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.civiltalaica.it\\\/cms\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/witila_pinochet-300x219.jpg\",\"contentUrl\":\"http:\\\/\\\/www.civiltalaica.it\\\/cms\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/witila_pinochet-300x219.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/evviva-wojtyla-santo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evviva Wojtyla santo!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/\",\"name\":\"Associazione Culturale Civilt\u00e0 Laica\",\"description\":\"Per un movimento culturale volto a difendere la Laicit\u00e0 dello Stato.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/#\\\/schema\\\/person\\\/4efef56f866329a1e0943eb27336df1d\",\"name\":\"alexjc\",\"url\":\"https:\\\/\\\/www.civiltalaica.it\\\/cms\\\/author\\\/alexjc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evviva Wojtyla santo! - Associazione Culturale Civilt\u00e0 Laica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.civiltalaica.it\/cms\/evviva-wojtyla-santo\/","og_locale":"it_IT","og_type":"article","og_title":"Evviva Wojtyla santo! - Associazione Culturale Civilt\u00e0 Laica","og_description":"&nbsp; L\u2019incidente che il 24 aprile, a Cevo (BS) ha determinato la morte di un povero ragazzo che, a causa di problemi motori, non avrebbe fatto in tempo a scostarsi nella caduta di una grossa croce lignea dedicata all\u2019ex papa polacco, \u00e8 parso a molti un segno del cielo contro la sua santificazione. Ci sarebbe [&hellip;]","og_url":"https:\/\/www.civiltalaica.it\/cms\/evviva-wojtyla-santo\/","og_site_name":"Associazione Culturale Civilt\u00e0 Laica","article_publisher":"https:\/\/www.facebook.com\/civiltalaica","article_published_time":"2014-05-03T14:01:57+00:00","article_modified_time":"2014-05-03T14:24:55+00:00","og_image":[{"url":"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2014\/05\/witila_pinochet-300x219.jpg","type":"","width":"","height":""}],"author":"alexjc","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"alexjc","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.civiltalaica.it\/cms\/evviva-wojtyla-santo\/#article","isPartOf":{"@id":"https:\/\/www.civiltalaica.it\/cms\/evviva-wojtyla-santo\/"},"author":{"name":"alexjc","@id":"https:\/\/www.civiltalaica.it\/cms\/#\/schema\/person\/4efef56f866329a1e0943eb27336df1d"},"headline":"Evviva Wojtyla santo!","datePublished":"2014-05-03T14:01:57+00:00","dateModified":"2014-05-03T14:24:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.civiltalaica.it\/cms\/evviva-wojtyla-santo\/"},"wordCount":907,"image":{"@id":"https:\/\/www.civiltalaica.it\/cms\/evviva-wojtyla-santo\/#primaryimage"},"thumbnailUrl":"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2014\/05\/witila_pinochet-300x219.jpg","keywords":["giovanni paolo ii","karol woitjla","maurizio magnani","santificazioni"],"articleSection":["articoli","riflessioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.civiltalaica.it\/cms\/evviva-wojtyla-santo\/","url":"https:\/\/www.civiltalaica.it\/cms\/evviva-wojtyla-santo\/","name":"Evviva Wojtyla santo! - Associazione Culturale Civilt\u00e0 Laica","isPartOf":{"@id":"https:\/\/www.civiltalaica.it\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.civiltalaica.it\/cms\/evviva-wojtyla-santo\/#primaryimage"},"image":{"@id":"https:\/\/www.civiltalaica.it\/cms\/evviva-wojtyla-santo\/#primaryimage"},"thumbnailUrl":"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2014\/05\/witila_pinochet-300x219.jpg","datePublished":"2014-05-03T14:01:57+00:00","dateModified":"2014-05-03T14:24:55+00:00","author":{"@id":"https:\/\/www.civiltalaica.it\/cms\/#\/schema\/person\/4efef56f866329a1e0943eb27336df1d"},"breadcrumb":{"@id":"https:\/\/www.civiltalaica.it\/cms\/evviva-wojtyla-santo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.civiltalaica.it\/cms\/evviva-wojtyla-santo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.civiltalaica.it\/cms\/evviva-wojtyla-santo\/#primaryimage","url":"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2014\/05\/witila_pinochet-300x219.jpg","contentUrl":"http:\/\/www.civiltalaica.it\/cms\/wp-content\/uploads\/2014\/05\/witila_pinochet-300x219.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.civiltalaica.it\/cms\/evviva-wojtyla-santo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.civiltalaica.it\/cms\/"},{"@type":"ListItem","position":2,"name":"Evviva Wojtyla santo!"}]},{"@type":"WebSite","@id":"https:\/\/www.civiltalaica.it\/cms\/#website","url":"https:\/\/www.civiltalaica.it\/cms\/","name":"Associazione Culturale Civilt\u00e0 Laica","description":"Per un movimento culturale volto a difendere la Laicit\u00e0 dello Stato.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.civiltalaica.it\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.civiltalaica.it\/cms\/#\/schema\/person\/4efef56f866329a1e0943eb27336df1d","name":"alexjc","url":"https:\/\/www.civiltalaica.it\/cms\/author\/alexjc\/"}]}},"_links":{"self":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts\/12315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/comments?post=12315"}],"version-history":[{"count":0,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/posts\/12315\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/media?parent=12315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/categories?post=12315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.civiltalaica.it\/cms\/wp-json\/wp\/v2\/tags?post=12315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}